{"id":18035,"date":"2022-11-18T00:07:30","date_gmt":"2022-11-18T00:07:30","guid":{"rendered":"https:\/\/www.radper.com\/produit\/detecteur-dinclinaison-inx360d-f99-b16-v15-pepperlfuchs\/"},"modified":"2026-05-13T16:43:45","modified_gmt":"2026-05-13T16:43:45","slug":"detecteur-dinclinaison-inx360d-f99-b16-v15-pepperlfuchs","status":"publish","type":"product","link":"https:\/\/www.radper.com\/en\/catalogs\/controle-de-process\/detecteurs-dinclinaison-et-dacceleration\/detecteur-dinclinaison-inx360d-f99-b16-v15-pepperlfuchs\/","title":{"rendered":"D\u00e9tecteur d&#8217;inclinaison INX360D-F99-B16-V15 PEPPERL+FUCHS"},"content":{"rendered":"<p>D\u00e9tecteur d&#8217;inclinaison INX360D-F99-B16-V15 PEPPERL+FUCHS, Type de d\u00e9tecteur D\u00e9tecteur d&#8217;inclinaison, \u00e0 1 axe, Gamme de mesure 0 &#8230; 360  \u00b0, pr\u00e9cision absolue \u2264 \u00b1 0,5  \u00b0, Retard \u00e0 l&#8217;appel \u2264 20 ms, R\u00e9solution \u2264 0,1  \u00b0, Reproductibilit\u00e9 \u2264 \u00b1 0,1  \u00b0, Influence de la temp\u00e9rature \u2264 0,027  \u00b0\/K<\/p>\n","protected":false},"excerpt":{"rendered":"<p>INX360D-F99-B16-V15<\/p>\n","protected":false},"featured_media":17943,"template":"","meta":{"_acf_changed":false},"product_brand":[],"product_cat":[2882],"product_tag":[],"class_list":{"0":"post-18035","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_cat-detecteurs-dinclinaison-et-dacceleration","7":"pa_marque-pepperlfuchs","9":"first","10":"instock","11":"featured","12":"taxable","13":"shipping-taxable","14":"product-type-simple"},"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v26.2 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>D\u00e9tecteur d&#039;inclinaison INX360D-F99-B16-V15 PEPPERL+FUCHS - Radper<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.radper.com\/en\/catalogs\/controle-de-process\/detecteurs-dinclinaison-et-dacceleration\/detecteur-dinclinaison-inx360d-f99-b16-v15-pepperlfuchs\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"D\u00e9tecteur d&#039;inclinaison INX360D-F99-B16-V15 PEPPERL+FUCHS - Radper\" \/>\n<meta property=\"og:description\" content=\"INX360D-F99-B16-V15\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.radper.com\/en\/catalogs\/controle-de-process\/detecteurs-dinclinaison-et-dacceleration\/detecteur-dinclinaison-inx360d-f99-b16-v15-pepperlfuchs\/\" \/>\n<meta property=\"og:site_name\" content=\"Radper\" \/>\n<meta property=\"article:modified_time\" content=\"2026-05-13T16:43:45+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.radper.com\/wp-content\/uploads\/2022\/11\/b248085a.png\" \/>\n\t<meta property=\"og:image:width\" content=\"545\" \/>\n\t<meta property=\"og:image:height\" content=\"600\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.radper.com\/en\/catalogs\/controle-de-process\/detecteurs-dinclinaison-et-dacceleration\/detecteur-dinclinaison-inx360d-f99-b16-v15-pepperlfuchs\/\",\"url\":\"https:\/\/www.radper.com\/en\/catalogs\/controle-de-process\/detecteurs-dinclinaison-et-dacceleration\/detecteur-dinclinaison-inx360d-f99-b16-v15-pepperlfuchs\/\",\"name\":\"D\u00e9tecteur d'inclinaison INX360D-F99-B16-V15 PEPPERL+FUCHS - Radper\",\"isPartOf\":{\"@id\":\"https:\/\/www.radper.com\/en\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.radper.com\/en\/catalogs\/controle-de-process\/detecteurs-dinclinaison-et-dacceleration\/detecteur-dinclinaison-inx360d-f99-b16-v15-pepperlfuchs\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.radper.com\/en\/catalogs\/controle-de-process\/detecteurs-dinclinaison-et-dacceleration\/detecteur-dinclinaison-inx360d-f99-b16-v15-pepperlfuchs\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.radper.com\/wp-content\/uploads\/2022\/11\/b248085a.png\",\"datePublished\":\"2022-11-18T00:07:30+00:00\",\"dateModified\":\"2026-05-13T16:43:45+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/www.radper.com\/en\/catalogs\/controle-de-process\/detecteurs-dinclinaison-et-dacceleration\/detecteur-dinclinaison-inx360d-f99-b16-v15-pepperlfuchs\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.radper.com\/en\/catalogs\/controle-de-process\/detecteurs-dinclinaison-et-dacceleration\/detecteur-dinclinaison-inx360d-f99-b16-v15-pepperlfuchs\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\/\/www.radper.com\/en\/catalogs\/controle-de-process\/detecteurs-dinclinaison-et-dacceleration\/detecteur-dinclinaison-inx360d-f99-b16-v15-pepperlfuchs\/#primaryimage\",\"url\":\"https:\/\/www.radper.com\/wp-content\/uploads\/2022\/11\/b248085a.png\",\"contentUrl\":\"https:\/\/www.radper.com\/wp-content\/uploads\/2022\/11\/b248085a.png\",\"width\":545,\"height\":600},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.radper.com\/en\/catalogs\/controle-de-process\/detecteurs-dinclinaison-et-dacceleration\/detecteur-dinclinaison-inx360d-f99-b16-v15-pepperlfuchs\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\/\/www.radper.com\/en\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Catalog\",\"item\":\"https:\/\/www.radper.com\/en\/catalog\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"D\u00e9tecteur d&rsquo;inclinaison INX360D-F99-B16-V15 PEPPERL+FUCHS\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.radper.com\/en\/#website\",\"url\":\"https:\/\/www.radper.com\/en\/\",\"name\":\"Radper\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\/\/www.radper.com\/en\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.radper.com\/en\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.radper.com\/en\/#organization\",\"name\":\"radper\",\"url\":\"https:\/\/www.radper.com\/en\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\/\/www.radper.com\/en\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/radper.com\/wp-content\/uploads\/2021\/04\/logo-wide-11.png\",\"contentUrl\":\"https:\/\/radper.com\/wp-content\/uploads\/2021\/04\/logo-wide-11.png\",\"width\":250,\"height\":110,\"caption\":\"radper\"},\"image\":{\"@id\":\"https:\/\/www.radper.com\/en\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"D\u00e9tecteur d'inclinaison INX360D-F99-B16-V15 PEPPERL+FUCHS - Radper","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.radper.com\/en\/catalogs\/controle-de-process\/detecteurs-dinclinaison-et-dacceleration\/detecteur-dinclinaison-inx360d-f99-b16-v15-pepperlfuchs\/","og_locale":"en_US","og_type":"article","og_title":"D\u00e9tecteur d'inclinaison INX360D-F99-B16-V15 PEPPERL+FUCHS - Radper","og_description":"INX360D-F99-B16-V15","og_url":"https:\/\/www.radper.com\/en\/catalogs\/controle-de-process\/detecteurs-dinclinaison-et-dacceleration\/detecteur-dinclinaison-inx360d-f99-b16-v15-pepperlfuchs\/","og_site_name":"Radper","article_modified_time":"2026-05-13T16:43:45+00:00","og_image":[{"width":545,"height":600,"url":"https:\/\/www.radper.com\/wp-content\/uploads\/2022\/11\/b248085a.png","type":"image\/png"}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.radper.com\/en\/catalogs\/controle-de-process\/detecteurs-dinclinaison-et-dacceleration\/detecteur-dinclinaison-inx360d-f99-b16-v15-pepperlfuchs\/","url":"https:\/\/www.radper.com\/en\/catalogs\/controle-de-process\/detecteurs-dinclinaison-et-dacceleration\/detecteur-dinclinaison-inx360d-f99-b16-v15-pepperlfuchs\/","name":"D\u00e9tecteur d'inclinaison INX360D-F99-B16-V15 PEPPERL+FUCHS - Radper","isPartOf":{"@id":"https:\/\/www.radper.com\/en\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.radper.com\/en\/catalogs\/controle-de-process\/detecteurs-dinclinaison-et-dacceleration\/detecteur-dinclinaison-inx360d-f99-b16-v15-pepperlfuchs\/#primaryimage"},"image":{"@id":"https:\/\/www.radper.com\/en\/catalogs\/controle-de-process\/detecteurs-dinclinaison-et-dacceleration\/detecteur-dinclinaison-inx360d-f99-b16-v15-pepperlfuchs\/#primaryimage"},"thumbnailUrl":"https:\/\/www.radper.com\/wp-content\/uploads\/2022\/11\/b248085a.png","datePublished":"2022-11-18T00:07:30+00:00","dateModified":"2026-05-13T16:43:45+00:00","breadcrumb":{"@id":"https:\/\/www.radper.com\/en\/catalogs\/controle-de-process\/detecteurs-dinclinaison-et-dacceleration\/detecteur-dinclinaison-inx360d-f99-b16-v15-pepperlfuchs\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.radper.com\/en\/catalogs\/controle-de-process\/detecteurs-dinclinaison-et-dacceleration\/detecteur-dinclinaison-inx360d-f99-b16-v15-pepperlfuchs\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/www.radper.com\/en\/catalogs\/controle-de-process\/detecteurs-dinclinaison-et-dacceleration\/detecteur-dinclinaison-inx360d-f99-b16-v15-pepperlfuchs\/#primaryimage","url":"https:\/\/www.radper.com\/wp-content\/uploads\/2022\/11\/b248085a.png","contentUrl":"https:\/\/www.radper.com\/wp-content\/uploads\/2022\/11\/b248085a.png","width":545,"height":600},{"@type":"BreadcrumbList","@id":"https:\/\/www.radper.com\/en\/catalogs\/controle-de-process\/detecteurs-dinclinaison-et-dacceleration\/detecteur-dinclinaison-inx360d-f99-b16-v15-pepperlfuchs\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/www.radper.com\/en\/"},{"@type":"ListItem","position":2,"name":"Catalog","item":"https:\/\/www.radper.com\/en\/catalog\/"},{"@type":"ListItem","position":3,"name":"D\u00e9tecteur d&rsquo;inclinaison INX360D-F99-B16-V15 PEPPERL+FUCHS"}]},{"@type":"WebSite","@id":"https:\/\/www.radper.com\/en\/#website","url":"https:\/\/www.radper.com\/en\/","name":"Radper","description":"","publisher":{"@id":"https:\/\/www.radper.com\/en\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.radper.com\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/www.radper.com\/en\/#organization","name":"radper","url":"https:\/\/www.radper.com\/en\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/www.radper.com\/en\/#\/schema\/logo\/image\/","url":"https:\/\/radper.com\/wp-content\/uploads\/2021\/04\/logo-wide-11.png","contentUrl":"https:\/\/radper.com\/wp-content\/uploads\/2021\/04\/logo-wide-11.png","width":250,"height":110,"caption":"radper"},"image":{"@id":"https:\/\/www.radper.com\/en\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/www.radper.com\/en\/wp-json\/wp\/v2\/product\/18035","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.radper.com\/en\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/www.radper.com\/en\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.radper.com\/en\/wp-json\/wp\/v2\/media\/17943"}],"wp:attachment":[{"href":"https:\/\/www.radper.com\/en\/wp-json\/wp\/v2\/media?parent=18035"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/www.radper.com\/en\/wp-json\/wp\/v2\/product_brand?post=18035"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/www.radper.com\/en\/wp-json\/wp\/v2\/product_cat?post=18035"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/www.radper.com\/en\/wp-json\/wp\/v2\/product_tag?post=18035"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}