{"id":21164,"date":"2022-11-25T16:03:18","date_gmt":"2022-11-25T16:03:18","guid":{"rendered":"https:\/\/www.radper.com\/produit\/disjoncteur-electronique-8-canaux-tension-dentree-24-v-dc-reglable-1-10-a-io-link-787-1668-000-080-wago\/"},"modified":"2026-07-14T13:09:27","modified_gmt":"2026-07-14T13:09:27","slug":"disjoncteur-electronique-8-canaux-tension-dentree-24-v-dc-reglable-1-10-a-io-link-787-1668-000-080-wago","status":"publish","type":"product","link":"https:\/\/www.radper.com\/en\/catalogs\/electrical-equipment\/power-modules\/disjoncteur-electronique-8-canaux-tension-dentree-24-v-dc-reglable-1-10-a-io-link-787-1668-000-080-wago\/","title":{"rendered":"Disjoncteur \u00e9lectronique; 8 canaux; Tension d&#8217;entr\u00e9e 24\u00a0V DC; r\u00e9glable 1 \u2026 10 A; IO-Link 787-1668\/000-080 WAGO"},"content":{"rendered":"<p>Disjoncteur \u00e9lectronique; 8 canaux; Tension d&#8217;entr\u00e9e 24\u00a0V DC; r\u00e9glable 1 \u2026 10 A; IO-Link 787-1668\/000-080 WAGO, Tension d&#8217;entr\u00e9e Ue DC\u00a024\u00a0V, Plage de tension d&#8217;entr\u00e9e DC\u00a018 \u2026 30\u00a0V<\/p>\n","protected":false},"excerpt":{"rendered":"<p>787-1668\/000-080<\/p>\n","protected":false},"featured_media":37802,"template":"","meta":{"_acf_changed":false},"product_brand":[],"product_cat":[13468],"product_tag":[],"class_list":{"0":"post-21164","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_cat-power-modules","7":"pa_marque-wago","9":"first","10":"instock","11":"featured","12":"taxable","13":"shipping-taxable","14":"product-type-simple"},"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v26.2 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Disjoncteur \u00e9lectronique; 8 canaux; Tension d&#039;entr\u00e9e 24\u00a0V DC; r\u00e9glable 1 \u2026 10 A; IO-Link 787-1668\/000-080 WAGO - Radper<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.radper.com\/en\/catalogs\/electrical-equipment\/power-modules\/disjoncteur-electronique-8-canaux-tension-dentree-24-v-dc-reglable-1-10-a-io-link-787-1668-000-080-wago\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Disjoncteur \u00e9lectronique; 8 canaux; Tension d&#039;entr\u00e9e 24\u00a0V DC; r\u00e9glable 1 \u2026 10 A; IO-Link 787-1668\/000-080 WAGO - Radper\" \/>\n<meta property=\"og:description\" content=\"787-1668\/000-080\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.radper.com\/en\/catalogs\/electrical-equipment\/power-modules\/disjoncteur-electronique-8-canaux-tension-dentree-24-v-dc-reglable-1-10-a-io-link-787-1668-000-080-wago\/\" \/>\n<meta property=\"og:site_name\" content=\"Radper\" \/>\n<meta property=\"article:modified_time\" content=\"2026-07-14T13:09:27+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.radper.com\/wp-content\/uploads\/2022\/12\/1024-0200002700029faf000100b6-DE.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"600\" \/>\n\t<meta property=\"og:image:height\" content=\"600\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.radper.com\/en\/catalogs\/electrical-equipment\/power-modules\/disjoncteur-electronique-8-canaux-tension-dentree-24-v-dc-reglable-1-10-a-io-link-787-1668-000-080-wago\/\",\"url\":\"https:\/\/www.radper.com\/en\/catalogs\/electrical-equipment\/power-modules\/disjoncteur-electronique-8-canaux-tension-dentree-24-v-dc-reglable-1-10-a-io-link-787-1668-000-080-wago\/\",\"name\":\"Disjoncteur \u00e9lectronique; 8 canaux; Tension d'entr\u00e9e 24\u00a0V DC; r\u00e9glable 1 \u2026 10 A; IO-Link 787-1668\/000-080 WAGO - Radper\",\"isPartOf\":{\"@id\":\"https:\/\/www.radper.com\/en\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.radper.com\/en\/catalogs\/electrical-equipment\/power-modules\/disjoncteur-electronique-8-canaux-tension-dentree-24-v-dc-reglable-1-10-a-io-link-787-1668-000-080-wago\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.radper.com\/en\/catalogs\/electrical-equipment\/power-modules\/disjoncteur-electronique-8-canaux-tension-dentree-24-v-dc-reglable-1-10-a-io-link-787-1668-000-080-wago\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.radper.com\/wp-content\/uploads\/2022\/12\/1024-0200002700029faf000100b6-DE.jpg\",\"datePublished\":\"2022-11-25T16:03:18+00:00\",\"dateModified\":\"2026-07-14T13:09:27+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/www.radper.com\/en\/catalogs\/electrical-equipment\/power-modules\/disjoncteur-electronique-8-canaux-tension-dentree-24-v-dc-reglable-1-10-a-io-link-787-1668-000-080-wago\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.radper.com\/en\/catalogs\/electrical-equipment\/power-modules\/disjoncteur-electronique-8-canaux-tension-dentree-24-v-dc-reglable-1-10-a-io-link-787-1668-000-080-wago\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\/\/www.radper.com\/en\/catalogs\/electrical-equipment\/power-modules\/disjoncteur-electronique-8-canaux-tension-dentree-24-v-dc-reglable-1-10-a-io-link-787-1668-000-080-wago\/#primaryimage\",\"url\":\"https:\/\/www.radper.com\/wp-content\/uploads\/2022\/12\/1024-0200002700029faf000100b6-DE.jpg\",\"contentUrl\":\"https:\/\/www.radper.com\/wp-content\/uploads\/2022\/12\/1024-0200002700029faf000100b6-DE.jpg\",\"width\":600,\"height\":600},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.radper.com\/en\/catalogs\/electrical-equipment\/power-modules\/disjoncteur-electronique-8-canaux-tension-dentree-24-v-dc-reglable-1-10-a-io-link-787-1668-000-080-wago\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\/\/www.radper.com\/en\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Catalog\",\"item\":\"https:\/\/www.radper.com\/en\/catalog\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Disjoncteur \u00e9lectronique; 8 canaux; Tension d&rsquo;entr\u00e9e 24\u00a0V DC; r\u00e9glable 1 \u2026 10 A; IO-Link 787-1668\/000-080 WAGO\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.radper.com\/en\/#website\",\"url\":\"https:\/\/www.radper.com\/en\/\",\"name\":\"Radper\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\/\/www.radper.com\/en\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.radper.com\/en\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.radper.com\/en\/#organization\",\"name\":\"radper\",\"url\":\"https:\/\/www.radper.com\/en\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\/\/www.radper.com\/en\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/radper.com\/wp-content\/uploads\/2021\/04\/logo-wide-11.png\",\"contentUrl\":\"https:\/\/radper.com\/wp-content\/uploads\/2021\/04\/logo-wide-11.png\",\"width\":250,\"height\":110,\"caption\":\"radper\"},\"image\":{\"@id\":\"https:\/\/www.radper.com\/en\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Disjoncteur \u00e9lectronique; 8 canaux; Tension d'entr\u00e9e 24\u00a0V DC; r\u00e9glable 1 \u2026 10 A; IO-Link 787-1668\/000-080 WAGO - Radper","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.radper.com\/en\/catalogs\/electrical-equipment\/power-modules\/disjoncteur-electronique-8-canaux-tension-dentree-24-v-dc-reglable-1-10-a-io-link-787-1668-000-080-wago\/","og_locale":"en_US","og_type":"article","og_title":"Disjoncteur \u00e9lectronique; 8 canaux; Tension d'entr\u00e9e 24\u00a0V DC; r\u00e9glable 1 \u2026 10 A; IO-Link 787-1668\/000-080 WAGO - Radper","og_description":"787-1668\/000-080","og_url":"https:\/\/www.radper.com\/en\/catalogs\/electrical-equipment\/power-modules\/disjoncteur-electronique-8-canaux-tension-dentree-24-v-dc-reglable-1-10-a-io-link-787-1668-000-080-wago\/","og_site_name":"Radper","article_modified_time":"2026-07-14T13:09:27+00:00","og_image":[{"width":600,"height":600,"url":"https:\/\/www.radper.com\/wp-content\/uploads\/2022\/12\/1024-0200002700029faf000100b6-DE.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.radper.com\/en\/catalogs\/electrical-equipment\/power-modules\/disjoncteur-electronique-8-canaux-tension-dentree-24-v-dc-reglable-1-10-a-io-link-787-1668-000-080-wago\/","url":"https:\/\/www.radper.com\/en\/catalogs\/electrical-equipment\/power-modules\/disjoncteur-electronique-8-canaux-tension-dentree-24-v-dc-reglable-1-10-a-io-link-787-1668-000-080-wago\/","name":"Disjoncteur \u00e9lectronique; 8 canaux; Tension d'entr\u00e9e 24\u00a0V DC; r\u00e9glable 1 \u2026 10 A; IO-Link 787-1668\/000-080 WAGO - Radper","isPartOf":{"@id":"https:\/\/www.radper.com\/en\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.radper.com\/en\/catalogs\/electrical-equipment\/power-modules\/disjoncteur-electronique-8-canaux-tension-dentree-24-v-dc-reglable-1-10-a-io-link-787-1668-000-080-wago\/#primaryimage"},"image":{"@id":"https:\/\/www.radper.com\/en\/catalogs\/electrical-equipment\/power-modules\/disjoncteur-electronique-8-canaux-tension-dentree-24-v-dc-reglable-1-10-a-io-link-787-1668-000-080-wago\/#primaryimage"},"thumbnailUrl":"https:\/\/www.radper.com\/wp-content\/uploads\/2022\/12\/1024-0200002700029faf000100b6-DE.jpg","datePublished":"2022-11-25T16:03:18+00:00","dateModified":"2026-07-14T13:09:27+00:00","breadcrumb":{"@id":"https:\/\/www.radper.com\/en\/catalogs\/electrical-equipment\/power-modules\/disjoncteur-electronique-8-canaux-tension-dentree-24-v-dc-reglable-1-10-a-io-link-787-1668-000-080-wago\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.radper.com\/en\/catalogs\/electrical-equipment\/power-modules\/disjoncteur-electronique-8-canaux-tension-dentree-24-v-dc-reglable-1-10-a-io-link-787-1668-000-080-wago\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/www.radper.com\/en\/catalogs\/electrical-equipment\/power-modules\/disjoncteur-electronique-8-canaux-tension-dentree-24-v-dc-reglable-1-10-a-io-link-787-1668-000-080-wago\/#primaryimage","url":"https:\/\/www.radper.com\/wp-content\/uploads\/2022\/12\/1024-0200002700029faf000100b6-DE.jpg","contentUrl":"https:\/\/www.radper.com\/wp-content\/uploads\/2022\/12\/1024-0200002700029faf000100b6-DE.jpg","width":600,"height":600},{"@type":"BreadcrumbList","@id":"https:\/\/www.radper.com\/en\/catalogs\/electrical-equipment\/power-modules\/disjoncteur-electronique-8-canaux-tension-dentree-24-v-dc-reglable-1-10-a-io-link-787-1668-000-080-wago\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/www.radper.com\/en\/"},{"@type":"ListItem","position":2,"name":"Catalog","item":"https:\/\/www.radper.com\/en\/catalog\/"},{"@type":"ListItem","position":3,"name":"Disjoncteur \u00e9lectronique; 8 canaux; Tension d&rsquo;entr\u00e9e 24\u00a0V DC; r\u00e9glable 1 \u2026 10 A; IO-Link 787-1668\/000-080 WAGO"}]},{"@type":"WebSite","@id":"https:\/\/www.radper.com\/en\/#website","url":"https:\/\/www.radper.com\/en\/","name":"Radper","description":"","publisher":{"@id":"https:\/\/www.radper.com\/en\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.radper.com\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/www.radper.com\/en\/#organization","name":"radper","url":"https:\/\/www.radper.com\/en\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/www.radper.com\/en\/#\/schema\/logo\/image\/","url":"https:\/\/radper.com\/wp-content\/uploads\/2021\/04\/logo-wide-11.png","contentUrl":"https:\/\/radper.com\/wp-content\/uploads\/2021\/04\/logo-wide-11.png","width":250,"height":110,"caption":"radper"},"image":{"@id":"https:\/\/www.radper.com\/en\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/www.radper.com\/en\/wp-json\/wp\/v2\/product\/21164","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.radper.com\/en\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/www.radper.com\/en\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.radper.com\/en\/wp-json\/wp\/v2\/media\/37802"}],"wp:attachment":[{"href":"https:\/\/www.radper.com\/en\/wp-json\/wp\/v2\/media?parent=21164"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/www.radper.com\/en\/wp-json\/wp\/v2\/product_brand?post=21164"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/www.radper.com\/en\/wp-json\/wp\/v2\/product_cat?post=21164"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/www.radper.com\/en\/wp-json\/wp\/v2\/product_tag?post=21164"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}