{"id":23848,"date":"2022-11-29T17:01:10","date_gmt":"2022-11-29T17:01:10","guid":{"rendered":"https:\/\/www.radper.com\/produit\/robinet-a-boisseau-spherique-modele-3-voies-femelle-bsp-passage-en-t-tecofi\/"},"modified":"2026-05-11T07:49:47","modified_gmt":"2026-05-11T07:49:47","slug":"robinet-a-boisseau-spherique-modele-3-voies-femelle-bsp-passage-en-t-tecofi","status":"publish","type":"product","link":"https:\/\/www.radper.com\/en\/catalogs\/pumps-and-valves\/ball-valves\/robinet-a-boisseau-spherique-modele-3-voies-femelle-bsp-passage-en-t-tecofi\/","title":{"rendered":"Robinet \u00e0 boisseau sph\u00e9rique mod\u00e8le 3 voies femelle BSP \u2013 Passage en T TECOFI"},"content":{"rendered":"<p>Robinet \u00e0 boisseau sph\u00e9rique mod\u00e8le 3 voies femelle BSP \u2013 Passage en T TECOFI, Mat\u00e9riaux du corps LAITON, Nature de la sph\u00e8re LAITON, Pression 16 BAR, Raccordement FEMELLE BSP, Contact \u00e9tanch\u00e9it\u00e9 PTFE, Actionneur POIGNEE ROUGE<\/p>\n","protected":false},"excerpt":{"rendered":"<p>BS1167<\/p>\n","protected":false},"featured_media":22861,"template":"","meta":{"_acf_changed":false},"product_brand":[],"product_cat":[13422],"product_tag":[],"class_list":{"0":"post-23848","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_cat-ball-valves","7":"pa_marque-tecofi","9":"first","10":"instock","11":"featured","12":"taxable","13":"shipping-taxable","14":"product-type-simple"},"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v26.2 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Robinet \u00e0 boisseau sph\u00e9rique mod\u00e8le 3 voies femelle BSP \u2013 Passage en T TECOFI - Radper<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.radper.com\/en\/catalogs\/pumps-and-valves\/ball-valves\/robinet-a-boisseau-spherique-modele-3-voies-femelle-bsp-passage-en-t-tecofi\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Robinet \u00e0 boisseau sph\u00e9rique mod\u00e8le 3 voies femelle BSP \u2013 Passage en T TECOFI - Radper\" \/>\n<meta property=\"og:description\" content=\"BS1167\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.radper.com\/en\/catalogs\/pumps-and-valves\/ball-valves\/robinet-a-boisseau-spherique-modele-3-voies-femelle-bsp-passage-en-t-tecofi\/\" \/>\n<meta property=\"og:site_name\" content=\"Radper\" \/>\n<meta property=\"article:modified_time\" content=\"2026-05-11T07:49:47+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.radper.com\/wp-content\/uploads\/2022\/11\/BS1167.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"654\" \/>\n\t<meta property=\"og:image:height\" content=\"600\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.radper.com\/en\/catalogs\/pumps-and-valves\/ball-valves\/robinet-a-boisseau-spherique-modele-3-voies-femelle-bsp-passage-en-t-tecofi\/\",\"url\":\"https:\/\/www.radper.com\/en\/catalogs\/pumps-and-valves\/ball-valves\/robinet-a-boisseau-spherique-modele-3-voies-femelle-bsp-passage-en-t-tecofi\/\",\"name\":\"Robinet \u00e0 boisseau sph\u00e9rique mod\u00e8le 3 voies femelle BSP \u2013 Passage en T TECOFI - Radper\",\"isPartOf\":{\"@id\":\"https:\/\/www.radper.com\/en\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.radper.com\/en\/catalogs\/pumps-and-valves\/ball-valves\/robinet-a-boisseau-spherique-modele-3-voies-femelle-bsp-passage-en-t-tecofi\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.radper.com\/en\/catalogs\/pumps-and-valves\/ball-valves\/robinet-a-boisseau-spherique-modele-3-voies-femelle-bsp-passage-en-t-tecofi\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.radper.com\/wp-content\/uploads\/2022\/11\/BS1167.jpg\",\"datePublished\":\"2022-11-29T17:01:10+00:00\",\"dateModified\":\"2026-05-11T07:49:47+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/www.radper.com\/en\/catalogs\/pumps-and-valves\/ball-valves\/robinet-a-boisseau-spherique-modele-3-voies-femelle-bsp-passage-en-t-tecofi\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.radper.com\/en\/catalogs\/pumps-and-valves\/ball-valves\/robinet-a-boisseau-spherique-modele-3-voies-femelle-bsp-passage-en-t-tecofi\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\/\/www.radper.com\/en\/catalogs\/pumps-and-valves\/ball-valves\/robinet-a-boisseau-spherique-modele-3-voies-femelle-bsp-passage-en-t-tecofi\/#primaryimage\",\"url\":\"https:\/\/www.radper.com\/wp-content\/uploads\/2022\/11\/BS1167.jpg\",\"contentUrl\":\"https:\/\/www.radper.com\/wp-content\/uploads\/2022\/11\/BS1167.jpg\",\"width\":654,\"height\":600},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.radper.com\/en\/catalogs\/pumps-and-valves\/ball-valves\/robinet-a-boisseau-spherique-modele-3-voies-femelle-bsp-passage-en-t-tecofi\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\/\/www.radper.com\/en\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Catalog\",\"item\":\"https:\/\/www.radper.com\/en\/catalog\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Robinet \u00e0 boisseau sph\u00e9rique mod\u00e8le 3 voies femelle BSP \u2013 Passage en T TECOFI\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.radper.com\/en\/#website\",\"url\":\"https:\/\/www.radper.com\/en\/\",\"name\":\"Radper\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\/\/www.radper.com\/en\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.radper.com\/en\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.radper.com\/en\/#organization\",\"name\":\"radper\",\"url\":\"https:\/\/www.radper.com\/en\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\/\/www.radper.com\/en\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/radper.com\/wp-content\/uploads\/2021\/04\/logo-wide-11.png\",\"contentUrl\":\"https:\/\/radper.com\/wp-content\/uploads\/2021\/04\/logo-wide-11.png\",\"width\":250,\"height\":110,\"caption\":\"radper\"},\"image\":{\"@id\":\"https:\/\/www.radper.com\/en\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Robinet \u00e0 boisseau sph\u00e9rique mod\u00e8le 3 voies femelle BSP \u2013 Passage en T TECOFI - Radper","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.radper.com\/en\/catalogs\/pumps-and-valves\/ball-valves\/robinet-a-boisseau-spherique-modele-3-voies-femelle-bsp-passage-en-t-tecofi\/","og_locale":"en_US","og_type":"article","og_title":"Robinet \u00e0 boisseau sph\u00e9rique mod\u00e8le 3 voies femelle BSP \u2013 Passage en T TECOFI - Radper","og_description":"BS1167","og_url":"https:\/\/www.radper.com\/en\/catalogs\/pumps-and-valves\/ball-valves\/robinet-a-boisseau-spherique-modele-3-voies-femelle-bsp-passage-en-t-tecofi\/","og_site_name":"Radper","article_modified_time":"2026-05-11T07:49:47+00:00","og_image":[{"width":654,"height":600,"url":"https:\/\/www.radper.com\/wp-content\/uploads\/2022\/11\/BS1167.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.radper.com\/en\/catalogs\/pumps-and-valves\/ball-valves\/robinet-a-boisseau-spherique-modele-3-voies-femelle-bsp-passage-en-t-tecofi\/","url":"https:\/\/www.radper.com\/en\/catalogs\/pumps-and-valves\/ball-valves\/robinet-a-boisseau-spherique-modele-3-voies-femelle-bsp-passage-en-t-tecofi\/","name":"Robinet \u00e0 boisseau sph\u00e9rique mod\u00e8le 3 voies femelle BSP \u2013 Passage en T TECOFI - Radper","isPartOf":{"@id":"https:\/\/www.radper.com\/en\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.radper.com\/en\/catalogs\/pumps-and-valves\/ball-valves\/robinet-a-boisseau-spherique-modele-3-voies-femelle-bsp-passage-en-t-tecofi\/#primaryimage"},"image":{"@id":"https:\/\/www.radper.com\/en\/catalogs\/pumps-and-valves\/ball-valves\/robinet-a-boisseau-spherique-modele-3-voies-femelle-bsp-passage-en-t-tecofi\/#primaryimage"},"thumbnailUrl":"https:\/\/www.radper.com\/wp-content\/uploads\/2022\/11\/BS1167.jpg","datePublished":"2022-11-29T17:01:10+00:00","dateModified":"2026-05-11T07:49:47+00:00","breadcrumb":{"@id":"https:\/\/www.radper.com\/en\/catalogs\/pumps-and-valves\/ball-valves\/robinet-a-boisseau-spherique-modele-3-voies-femelle-bsp-passage-en-t-tecofi\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.radper.com\/en\/catalogs\/pumps-and-valves\/ball-valves\/robinet-a-boisseau-spherique-modele-3-voies-femelle-bsp-passage-en-t-tecofi\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/www.radper.com\/en\/catalogs\/pumps-and-valves\/ball-valves\/robinet-a-boisseau-spherique-modele-3-voies-femelle-bsp-passage-en-t-tecofi\/#primaryimage","url":"https:\/\/www.radper.com\/wp-content\/uploads\/2022\/11\/BS1167.jpg","contentUrl":"https:\/\/www.radper.com\/wp-content\/uploads\/2022\/11\/BS1167.jpg","width":654,"height":600},{"@type":"BreadcrumbList","@id":"https:\/\/www.radper.com\/en\/catalogs\/pumps-and-valves\/ball-valves\/robinet-a-boisseau-spherique-modele-3-voies-femelle-bsp-passage-en-t-tecofi\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/www.radper.com\/en\/"},{"@type":"ListItem","position":2,"name":"Catalog","item":"https:\/\/www.radper.com\/en\/catalog\/"},{"@type":"ListItem","position":3,"name":"Robinet \u00e0 boisseau sph\u00e9rique mod\u00e8le 3 voies femelle BSP \u2013 Passage en T TECOFI"}]},{"@type":"WebSite","@id":"https:\/\/www.radper.com\/en\/#website","url":"https:\/\/www.radper.com\/en\/","name":"Radper","description":"","publisher":{"@id":"https:\/\/www.radper.com\/en\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.radper.com\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/www.radper.com\/en\/#organization","name":"radper","url":"https:\/\/www.radper.com\/en\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/www.radper.com\/en\/#\/schema\/logo\/image\/","url":"https:\/\/radper.com\/wp-content\/uploads\/2021\/04\/logo-wide-11.png","contentUrl":"https:\/\/radper.com\/wp-content\/uploads\/2021\/04\/logo-wide-11.png","width":250,"height":110,"caption":"radper"},"image":{"@id":"https:\/\/www.radper.com\/en\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/www.radper.com\/en\/wp-json\/wp\/v2\/product\/23848","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.radper.com\/en\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/www.radper.com\/en\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.radper.com\/en\/wp-json\/wp\/v2\/media\/22861"}],"wp:attachment":[{"href":"https:\/\/www.radper.com\/en\/wp-json\/wp\/v2\/media?parent=23848"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/www.radper.com\/en\/wp-json\/wp\/v2\/product_brand?post=23848"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/www.radper.com\/en\/wp-json\/wp\/v2\/product_cat?post=23848"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/www.radper.com\/en\/wp-json\/wp\/v2\/product_tag?post=23848"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}