{"id":28242,"date":"2022-12-06T13:50:34","date_gmt":"2022-12-06T13:50:34","guid":{"rendered":"https:\/\/www.radper.com\/produit\/chaussures-tst-hta-pour-protection-de-tension-de-pas-taille-41-mv-232-1-41-catu\/"},"modified":"2026-05-13T10:35:58","modified_gmt":"2026-05-13T10:35:58","slug":"chaussures-tst-hta-protection-tension-pas-mv-232-1-41-catu","status":"publish","type":"product","link":"https:\/\/www.radper.com\/en\/catalogs\/epi-outillage\/epi\/protection-du-pied-equipements-de-securite\/chaussures-tst-hta-protection-tension-pas-mv-232-1-41-catu\/","title":{"rendered":"Chaussures TST HTA pour protection de tension de pas taille 41 MV-232\/1-41 CATU"},"content":{"rendered":"<p>Chaussures TST HTA pour protection de tension de pas, taille 41 MV-232\/1-41 CATU, Taille 41<\/p>\n","protected":false},"excerpt":{"rendered":"<p>MV-232\/1-41<\/p>\n","protected":false},"featured_media":27842,"template":"","meta":{"_acf_changed":false},"product_brand":[],"product_cat":[9967],"product_tag":[],"class_list":{"0":"post-28242","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_cat-protection-du-pied-equipements-de-securite","7":"pa_marque-catu","9":"first","10":"instock","11":"featured","12":"taxable","13":"shipping-taxable","14":"product-type-simple"},"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v26.2 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Chaussures TST HTA pour protection de tension de pas taille 41 MV-232\/1-41 CATU - Radper<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.radper.com\/en\/catalogs\/epi-outillage\/epi\/protection-du-pied-equipements-de-securite\/chaussures-tst-hta-protection-tension-pas-mv-232-1-41-catu\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Chaussures TST HTA pour protection de tension de pas taille 41 MV-232\/1-41 CATU - Radper\" \/>\n<meta property=\"og:description\" content=\"MV-232\/1-41\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.radper.com\/en\/catalogs\/epi-outillage\/epi\/protection-du-pied-equipements-de-securite\/chaussures-tst-hta-protection-tension-pas-mv-232-1-41-catu\/\" \/>\n<meta property=\"og:site_name\" content=\"Radper\" \/>\n<meta property=\"article:modified_time\" content=\"2026-05-13T10:35:58+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.radper.com\/wp-content\/uploads\/2022\/12\/MV-2321_PIC001.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"600\" \/>\n\t<meta property=\"og:image:height\" content=\"600\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.radper.com\/en\/catalogs\/epi-outillage\/epi\/protection-du-pied-equipements-de-securite\/chaussures-tst-hta-protection-tension-pas-mv-232-1-41-catu\/\",\"url\":\"https:\/\/www.radper.com\/en\/catalogs\/epi-outillage\/epi\/protection-du-pied-equipements-de-securite\/chaussures-tst-hta-protection-tension-pas-mv-232-1-41-catu\/\",\"name\":\"Chaussures TST HTA pour protection de tension de pas taille 41 MV-232\/1-41 CATU - Radper\",\"isPartOf\":{\"@id\":\"https:\/\/www.radper.com\/en\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.radper.com\/en\/catalogs\/epi-outillage\/epi\/protection-du-pied-equipements-de-securite\/chaussures-tst-hta-protection-tension-pas-mv-232-1-41-catu\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.radper.com\/en\/catalogs\/epi-outillage\/epi\/protection-du-pied-equipements-de-securite\/chaussures-tst-hta-protection-tension-pas-mv-232-1-41-catu\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.radper.com\/wp-content\/uploads\/2022\/12\/MV-2321_PIC001.jpg\",\"datePublished\":\"2022-12-06T13:50:34+00:00\",\"dateModified\":\"2026-05-13T10:35:58+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/www.radper.com\/en\/catalogs\/epi-outillage\/epi\/protection-du-pied-equipements-de-securite\/chaussures-tst-hta-protection-tension-pas-mv-232-1-41-catu\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.radper.com\/en\/catalogs\/epi-outillage\/epi\/protection-du-pied-equipements-de-securite\/chaussures-tst-hta-protection-tension-pas-mv-232-1-41-catu\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\/\/www.radper.com\/en\/catalogs\/epi-outillage\/epi\/protection-du-pied-equipements-de-securite\/chaussures-tst-hta-protection-tension-pas-mv-232-1-41-catu\/#primaryimage\",\"url\":\"https:\/\/www.radper.com\/wp-content\/uploads\/2022\/12\/MV-2321_PIC001.jpg\",\"contentUrl\":\"https:\/\/www.radper.com\/wp-content\/uploads\/2022\/12\/MV-2321_PIC001.jpg\",\"width\":600,\"height\":600},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.radper.com\/en\/catalogs\/epi-outillage\/epi\/protection-du-pied-equipements-de-securite\/chaussures-tst-hta-protection-tension-pas-mv-232-1-41-catu\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\/\/www.radper.com\/en\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Catalog\",\"item\":\"https:\/\/www.radper.com\/en\/catalog\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Chaussures TST HTA pour protection de tension de pas taille 41 MV-232\/1-41 CATU\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.radper.com\/en\/#website\",\"url\":\"https:\/\/www.radper.com\/en\/\",\"name\":\"Radper\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\/\/www.radper.com\/en\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.radper.com\/en\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.radper.com\/en\/#organization\",\"name\":\"radper\",\"url\":\"https:\/\/www.radper.com\/en\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\/\/www.radper.com\/en\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/radper.com\/wp-content\/uploads\/2021\/04\/logo-wide-11.png\",\"contentUrl\":\"https:\/\/radper.com\/wp-content\/uploads\/2021\/04\/logo-wide-11.png\",\"width\":250,\"height\":110,\"caption\":\"radper\"},\"image\":{\"@id\":\"https:\/\/www.radper.com\/en\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Chaussures TST HTA pour protection de tension de pas taille 41 MV-232\/1-41 CATU - Radper","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.radper.com\/en\/catalogs\/epi-outillage\/epi\/protection-du-pied-equipements-de-securite\/chaussures-tst-hta-protection-tension-pas-mv-232-1-41-catu\/","og_locale":"en_US","og_type":"article","og_title":"Chaussures TST HTA pour protection de tension de pas taille 41 MV-232\/1-41 CATU - Radper","og_description":"MV-232\/1-41","og_url":"https:\/\/www.radper.com\/en\/catalogs\/epi-outillage\/epi\/protection-du-pied-equipements-de-securite\/chaussures-tst-hta-protection-tension-pas-mv-232-1-41-catu\/","og_site_name":"Radper","article_modified_time":"2026-05-13T10:35:58+00:00","og_image":[{"width":600,"height":600,"url":"https:\/\/www.radper.com\/wp-content\/uploads\/2022\/12\/MV-2321_PIC001.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.radper.com\/en\/catalogs\/epi-outillage\/epi\/protection-du-pied-equipements-de-securite\/chaussures-tst-hta-protection-tension-pas-mv-232-1-41-catu\/","url":"https:\/\/www.radper.com\/en\/catalogs\/epi-outillage\/epi\/protection-du-pied-equipements-de-securite\/chaussures-tst-hta-protection-tension-pas-mv-232-1-41-catu\/","name":"Chaussures TST HTA pour protection de tension de pas taille 41 MV-232\/1-41 CATU - Radper","isPartOf":{"@id":"https:\/\/www.radper.com\/en\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.radper.com\/en\/catalogs\/epi-outillage\/epi\/protection-du-pied-equipements-de-securite\/chaussures-tst-hta-protection-tension-pas-mv-232-1-41-catu\/#primaryimage"},"image":{"@id":"https:\/\/www.radper.com\/en\/catalogs\/epi-outillage\/epi\/protection-du-pied-equipements-de-securite\/chaussures-tst-hta-protection-tension-pas-mv-232-1-41-catu\/#primaryimage"},"thumbnailUrl":"https:\/\/www.radper.com\/wp-content\/uploads\/2022\/12\/MV-2321_PIC001.jpg","datePublished":"2022-12-06T13:50:34+00:00","dateModified":"2026-05-13T10:35:58+00:00","breadcrumb":{"@id":"https:\/\/www.radper.com\/en\/catalogs\/epi-outillage\/epi\/protection-du-pied-equipements-de-securite\/chaussures-tst-hta-protection-tension-pas-mv-232-1-41-catu\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.radper.com\/en\/catalogs\/epi-outillage\/epi\/protection-du-pied-equipements-de-securite\/chaussures-tst-hta-protection-tension-pas-mv-232-1-41-catu\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/www.radper.com\/en\/catalogs\/epi-outillage\/epi\/protection-du-pied-equipements-de-securite\/chaussures-tst-hta-protection-tension-pas-mv-232-1-41-catu\/#primaryimage","url":"https:\/\/www.radper.com\/wp-content\/uploads\/2022\/12\/MV-2321_PIC001.jpg","contentUrl":"https:\/\/www.radper.com\/wp-content\/uploads\/2022\/12\/MV-2321_PIC001.jpg","width":600,"height":600},{"@type":"BreadcrumbList","@id":"https:\/\/www.radper.com\/en\/catalogs\/epi-outillage\/epi\/protection-du-pied-equipements-de-securite\/chaussures-tst-hta-protection-tension-pas-mv-232-1-41-catu\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/www.radper.com\/en\/"},{"@type":"ListItem","position":2,"name":"Catalog","item":"https:\/\/www.radper.com\/en\/catalog\/"},{"@type":"ListItem","position":3,"name":"Chaussures TST HTA pour protection de tension de pas taille 41 MV-232\/1-41 CATU"}]},{"@type":"WebSite","@id":"https:\/\/www.radper.com\/en\/#website","url":"https:\/\/www.radper.com\/en\/","name":"Radper","description":"","publisher":{"@id":"https:\/\/www.radper.com\/en\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.radper.com\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/www.radper.com\/en\/#organization","name":"radper","url":"https:\/\/www.radper.com\/en\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/www.radper.com\/en\/#\/schema\/logo\/image\/","url":"https:\/\/radper.com\/wp-content\/uploads\/2021\/04\/logo-wide-11.png","contentUrl":"https:\/\/radper.com\/wp-content\/uploads\/2021\/04\/logo-wide-11.png","width":250,"height":110,"caption":"radper"},"image":{"@id":"https:\/\/www.radper.com\/en\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/www.radper.com\/en\/wp-json\/wp\/v2\/product\/28242","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.radper.com\/en\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/www.radper.com\/en\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.radper.com\/en\/wp-json\/wp\/v2\/media\/27842"}],"wp:attachment":[{"href":"https:\/\/www.radper.com\/en\/wp-json\/wp\/v2\/media?parent=28242"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/www.radper.com\/en\/wp-json\/wp\/v2\/product_brand?post=28242"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/www.radper.com\/en\/wp-json\/wp\/v2\/product_cat?post=28242"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/www.radper.com\/en\/wp-json\/wp\/v2\/product_tag?post=28242"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}